{"id":9017,"date":"2026-05-12T15:27:34","date_gmt":"2026-05-12T15:27:34","guid":{"rendered":"https:\/\/www.sukarne.com\/?p=9017"},"modified":"2026-05-12T18:03:21","modified_gmt":"2026-05-12T18:03:21","slug":"minisukarnianos-2026-el-corazon-de-sukarne-late-con-la-alegria-de-mas-de-5-mil-ninas-y-ninos","status":"publish","type":"post","link":"https:\/\/www.sukarne.com\/es_mx\/blog-de-notas\/minisukarnianos-2026-el-corazon-de-sukarne-late-con-la-alegria-de-mas-de-5-mil-ninas-y-ninos\/","title":{"rendered":"MiniSuKarnianos 2026: El coraz\u00f3n de SuKarne late con la alegr\u00eda de m\u00e1s de 5 mil ni\u00f1as y ni\u00f1os."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9017\" class=\"elementor elementor-9017\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3956c778 e-flex e-con-boxed e-con e-parent\" data-id=\"3956c778\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-186cb883 elementor-widget elementor-widget-text-editor\" data-id=\"186cb883\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><strong><i>En el marco del D\u00eda de la Ni\u00f1ez, SuKarne reafirma que la familia es el motor que impulsa el \u00e9xito operativo en sus centros de trabajo a nivel nacional.<\/i><\/strong><\/li><\/ul><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Culiac\u00e1n, Sinaloa. En una jornada hist\u00f3rica marcada por risas, diversi\u00f3n y un sentido de pertenencia, SuKarne celebr\u00f3 la 5.\u00aa edici\u00f3n de &#8220;<strong>MiniSuKarnianos<\/strong>&#8220;. Este evento, que ya es una tradici\u00f3n institucional, transform\u00f3 los centros operativos y oficinas en escenarios de magia para festejar el D\u00eda de la Ni\u00f1ez, al impactar en la calidad de vida de quienes d\u00eda con d\u00eda construyen la empresa.<\/span><\/p><p><span style=\"font-weight: 400;\">Este a\u00f1o, se festejan a <strong>5,647<\/strong> ni\u00f1as y ni\u00f1os de los distintos centros de trabajo del pa\u00eds y las oficinas centrales de Culiac\u00e1n. En esta edici\u00f3n se invit\u00f3 a los sobrinos de los colaboradores, que tiene como objetivo fortalecer el v\u00ednculo emocional, la inclusi\u00f3n y consolidar a <strong>SuKarne<\/strong> como una familia de trabajo que trasciende.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Adem\u00e1s de conectar con el lugar de trabajo de sus pap\u00e1s, los peque\u00f1os vivieron y disfrutaron de los recorridos tem\u00e1ticos, realizaron pintura de yesos, participaron en los juegos de feria y bailaron al ritmo de m\u00fasica en la minidisco.\u00a0<\/span><\/p><p style=\"padding-left: 40px;\"><em><span style=\"font-weight: 400;\">&#8220;Me encant\u00f3 haber ido al evento de los MiniSuKarnianos; los juegos y los dulces estuvieron muy divertidos. Fue una experiencia muy &#8221;chilo&#8217; <\/span><span style=\"font-weight: 400;\">(divertido)<\/span><span style=\"font-weight: 400;\"> porque pude jugar con muchos ni\u00f1os y me fascin\u00f3 estar en la feria. Lo que m\u00e1s disfrut\u00e9 del recorrido fueron las decoraciones de Mario Galaxy y K-Pop Demon Hunters&#8221; se\u00f1al\u00f3 Eder Fernando de 6 a\u00f1os.\u00a0<\/span><\/em><\/p><p><span style=\"font-weight: 400;\">Para SuKarne, este momento es m\u00e1s que log\u00edstica; es una apuesta por el equilibrio vital. Al decorar las \u00e1reas de trabajo en espacios de juego, se recuerda a cada integrante de la organizaci\u00f3n que el \u00e9xito de la operaci\u00f3n tiene su raz\u00f3n de ser en la calidad de vida y la felicidad de las familias que los esperan en casa.<\/span><\/p><p style=\"padding-left: 40px;\"><em>Everett \u00c1lvarez L\u00f3pez, Gerente de Personal Pecuario coment\u00f3: &#8220;Para nosotros como padres de familia, recibir a todos los MiniSuKarnianos en nuestro espacio de trabajo, fue una experiencia m\u00e1gica. Observamos c\u00f3mo cada rinc\u00f3n de la oficina se transform\u00f3 en color, alegr\u00eda y sorpresas. Ver sus rostros llenos de asombro y felicidad al entrar convirti\u00f3 esta edici\u00f3n en un momento memorable, que nos motiva para recibirlos\u00a0 el pr\u00f3ximo a\u00f1o&#8221;.<\/em><\/p><p><span style=\"font-weight: 400;\">Con cinco a\u00f1os de trayectoria, el programa MiniSuKarnianos se consolida como una herramienta clave de cultura organizacional. SuKarne reitera que estas acciones son fundamentales para que las nuevas generaciones conozcan de cerca el esfuerzo, la pasi\u00f3n y los valores que rigen el trabajo de sus familias, fomentando un orgullo de pertenencia que trasciende generaciones.<\/span>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4980da8 elementor-widget__width-initial elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4980da8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de Im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A1108.jpg\" alt=\"1M9A1108\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A9641.jpg\" alt=\"1M9A9641\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A9599.jpg\" alt=\"1M9A9599\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A0235.jpg\" alt=\"1M9A0235\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A9929.jpg\" alt=\"1M9A9929\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A0514.jpg\" alt=\"1M9A0514\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A9436.jpg\" alt=\"1M9A9436\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A0155.jpg\" alt=\"1M9A0155\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A0115.jpg\" alt=\"1M9A0115\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A9787.jpg\" alt=\"1M9A9787\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sukarne.com\/wp-content\/uploads\/2026\/05\/1M9A0197.jpg\" alt=\"1M9A0197\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda de la Ni\u00f1ez, SuKarne reafirma que la familia es el motor que impulsa el \u00e9xito operativo en sus centros de trabajo a nivel nacional. \u00a0 Culiac\u00e1n, Sinaloa. En una jornada hist\u00f3rica marcada por risas, diversi\u00f3n y un sentido de pertenencia, SuKarne celebr\u00f3 la 5.\u00aa edici\u00f3n de &#8220;MiniSuKarnianos&#8220;. Este evento, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[137,138],"tags":[],"class_list":["post-9017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de-notas","category-foto-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/posts\/9017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/comments?post=9017"}],"version-history":[{"count":18,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/posts\/9017\/revisions"}],"predecessor-version":[{"id":9050,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/posts\/9017\/revisions\/9050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/media\/9019"}],"wp:attachment":[{"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/media?parent=9017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/categories?post=9017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sukarne.com\/es_mx\/wp-json\/wp\/v2\/tags?post=9017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}